{"id":25101,"date":"2024-11-19T21:21:29","date_gmt":"2024-11-20T00:21:29","guid":{"rendered":"https:\/\/mastertrend.info\/?p=25101"},"modified":"2026-01-03T18:32:10","modified_gmt":"2026-01-03T21:32:10","slug":"amd-ryzen-7-9800x3d-review","status":"publish","type":"post","link":"https:\/\/mastertrend.info\/en\/revision-del-amd-ryzen-7-9800x3d\/","title":{"rendered":"AMD Ryzen 7 9800X3D Review"},"content":{"rendered":"<div id=\"article-body\">\n<h2>Revisi\u00f3n del AMD Ryzen 7 9800X3D: Desempe\u00f1o Gaming Devastador \ud83c\udfae\ud83d\udd25<\/h2>\n<p>El Ryzen 7 9800X3D de AMD, que cuesta $480, viene equipado con ocho n\u00facleos y 16 hilos, junto con una nueva versi\u00f3n de la tecnolog\u00eda 3D V-Cache de la empresa, que potencia los juegos de manera impresionante. Se posiciona como el procesador m\u00e1s r\u00e1pido para gaming en el mercado, y de manera contundente. \ud83c\udfc6<\/p>\n<p>AMD afirma que este chip es un 20% mejor que el \u00faltimo modelo insignia de Intel y un 8% m\u00e1s r\u00e1pido que el Ryzen 7 7800X3D de la generaci\u00f3n anterior. Sin embargo, nuestras pruebas demuestran que supera al modelo insignia actual de Intel, el Core 9 285K, por un asombroso 35% en promedio en nuestra bater\u00eda de pruebas. Incluso supera al chip de <a href=\"https:\/\/mastertrend.info\/tecnologia-pssr-ps5-pro\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"4049\">gaming<\/a> m\u00e1s r\u00e1pido de Intel, el Core i9-14900K, por un igualmente incre\u00edble 30% en promedio. \ud83d\ude80<\/p>\n<p>Por supuesto, las mejoras variar\u00e1n seg\u00fan el t\u00edtulo debido a las particularidades de la <a href=\"https:\/\/mastertrend.info\/atlas-de-boston-dynamics\/\" data-wpil-monitor-id=\"802\" target=\"_blank\">tecnolog\u00eda<\/a> 3D V-Cache. Aun as\u00ed, registramos un rendimiento incre\u00edble que consolida firmemente al Ryzen 9 9800X3D como el mejor CPU para gaming. \ud83d\udcaa<\/p>\n<p>AMD logr\u00f3 esta haza\u00f1a aprovechando su tecnolog\u00eda 3D V-Cache ya probada, que utiliza un chiplet de cach\u00e9 L3 apilado verticalmente de 64 MB para mejorar el rendimiento en juegos. Para mejorar a\u00fan m\u00e1s el desempe\u00f1o, AMD movi\u00f3 el chiplet de cach\u00e9 desde la parte superior del procesador hacia abajo, ofreciendo as\u00ed un mayor margen t\u00e9rmico. Esto permite tasas de reloj m\u00e1s altas, mientras que la cach\u00e9 adicional desbloquea el m\u00e1ximo <a href=\"https:\/\/mastertrend.info\/acelerar-computadora-windows-lenta-11-formas\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"1495\">rendimiento<\/a> de la arquitectura Zen 5. \ud83d\udd25\ud83d\udcc8<\/p>\n<p>Como estamos acostumbrados con los procesadores X3D <a href=\"https:\/\/mastertrend.info\/bloquear-sitios-web\/\" data-wpil-monitor-id=\"726\" target=\"_blank\">optimizados<\/a> para gaming, no todos los juegos se beneficiar\u00e1n de la tecnolog\u00eda, y algunos son incluso ligeramente m\u00e1s lentos (1 a 2%) que el modelo de la generaci\u00f3n anterior. No obstante, el chip mejora significativamente las tasas bajas del 1% incluso en esos t\u00edtulos. Las tasas bajas del 1% m\u00e1s altas tambi\u00e9n ayudar\u00e1n cuando est\u00e9s limitado por la GPU, como al jugar con resoluciones m\u00e1s altas. \ud83c\udfaf<\/p>\n<p>AMD ahora tambi\u00e9n ha habilitado el overclocking completo para el 9800X3D, lo cual hemos probado, permiti\u00e9ndote exprimir m\u00e1s rendimiento tanto en juegos como en trabajos de productividad. Hablando de eso, el nuevo dise\u00f1o tambi\u00e9n ayuda a eliminar algunas de las grandes penalizaciones en trabajos de productividad que a menudo se pagan por usar un procesador X3D optimizado para gaming, permitiendo que el 9800X3D iguale, e incluso a veces supere, a un CPU Ryzen 9000 de ocho n\u00facleos comparable en varias cargas de trabajo de productividad. \ud83d\udcbb\u26a1<\/p>\n<p>&nbsp;<\/p>\n<div id=\"slice-container-table-X8gKaYYfDhupCfLRQKe8j4-1M4445wpheYBamDBsHk7W0yI0h9DIw13\" class=\"slice-container table-wrapper table-X8gKaYYfDhupCfLRQKe8j4-1M4445wpheYBamDBsHk7W0yI0h9DIw13 slice-container-table\">\n<div class=\"table__container\">\n<table class=\"table__wrapper table__wrapper--inbodyContent table__wrapper--sticky table__wrapper--divider\">\n<caption class=\"table__caption table__caption--top table__caption--left\"><a href=\"https:\/\/mastertrend.info\/threadripper-7000\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"3695\">AMD Zen 5 Ryzen<\/a> 9000 &#8216;Granite Ridge' Specifications and Pricing<\/caption>\n<thead class=\"table__head\">\n<tr class=\"table__head__row\">\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\"><\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Street\/MSRP<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Arch<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Cores \/ Threads<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Base \/ Boost Clock (GHz)<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Cache (L2\/L3)<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">TDP \/ PPT<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Memory<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"table__body\">\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><a href=\"https:\/\/mastertrend.info\/ryzen-9-9950x-alcanza-los-7\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"424\">Ryzen 9 9950X<\/a><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$649<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">16 \/ 32<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.3 \/ 5.7<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">80MB (16+64)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">170W \/ 230W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 9 9900X<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$499<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">12 \/ 24<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.4 \/ 5.6<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">76MB (12+64)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">120W \/ 162W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong><a class=\"wpil_keyword_link\" href=\"https:\/\/mastertrend.info\/procesador-universal-risc-v\/\" target=\"_blank\"  rel=\"noopener\" title=\"Procesador universal RISC-V llegar\u00e1 en 2 a\u00f1os con CPU+GPU+DSP+FPGA \u26a1\ud83d\udd0d\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"15901\">Ryzen 7 9800X3D<\/a><\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>$480<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>Zen 5 X3D<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>8 \/ 16<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>4.7 \/ 5.2<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>104MB (8+96)<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>120W \/ 162W <\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>DDR5-5600<\/strong><\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 7 9700X<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$359<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">8 \/16<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.8 \/ 5.5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">40MB (8+32)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">65W \/ 88W \/ 105W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 5 9600X<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$279<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">6 \/ 12<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.9 \/ 5.4<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">38MB (6+32)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">65W \/ 88W \/ 105W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5600<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<aside class=\"hawk-nest\" data-block-type=\"embed\" data-model-name=\"AMD_Ryzen_7_9800X3D_Review:_Devastating_Gaming_Performance\" data-name=\"Inbody widget\" data-render-type=\"fte\" data-skip=\"phones\" data-widget-type=\"inbody\"><\/aside>\n<aside class=\"hawk-nest\" data-block-type=\"embed\" data-render-type=\"fte\" data-skip=\"dealsy\" data-widget-type=\"seasonal\"><\/aside>\n<p>&nbsp;<\/p>\n<p>\ud83d\udca5 El <a href=\"https:\/\/mastertrend.info\/amd-ryzen-8000g-con-ia\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"434\">Ryzen<\/a> 9 9800X3D, con un precio de $480, es el \u00fanico lanzamiento de AMD hoy, y estar\u00e1 disponible en las tiendas ma\u00f1ana. Este chip es la salvaci\u00f3n para los fan\u00e1ticos del <a title=\"Nintendo Switch 2: Clave para su \u00e9xito asegurado \ud83d\ude80\" href=\"https:\/\/mastertrend.info\/nintendo-switch-2\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"4450\">gaming<\/a> \ud83c\udfae, quienes se enfrentaron este a\u00f1o no solo a uno, sino a dos lanzamientos de chips decepcionantes.<\/p>\n<p>La serie Ryzen 9000 de AMD, impulsada por Zen 5, debut\u00f3 a principios de este a\u00f1o con ganancias de rendimiento en gaming poco impresionantes. Sin embargo, como ver\u00e1s en nuestras pruebas recientes para esta rese\u00f1a, las \u00faltimas actualizaciones de firmware y un ajuste en Windows han logrado exprimir m\u00e1s rendimiento. Intel tambi\u00e9n lanz\u00f3 su esperada serie Arrow Lake <a href=\"https:\/\/mastertrend.info\/ventas-del-core-ultra-200s\/\" data-wpil-monitor-id=\"1042\" target=\"_blank\">Core Ultra<\/a> hace solo dos semanas, pero esos chips no lograron igualar el rendimiento en gaming de sus chips de generaci\u00f3n anterior. \ud83d\ude1f Desafortunadamente, no hay una soluci\u00f3n evidente a la vista, lo que presagia un a\u00f1o decepcionante para los chips de gaming.<\/p>\n<p>El Ryzen 7 9800X3D cambia completamente el panorama, trayendo al mercado un chip de <a href=\"https:\/\/mastertrend.info\/las-mejores-laptops-para-gaming-2025\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"3349\">gaming<\/a> de primera calidad a un precio razonable dadas sus capacidades. Este chip se adapta a las placas madre AM5 existentes y no requerir\u00e1 los costosos componentes complementarios, como kits de RAM de alta velocidad, potentes sistemas de refrigeraci\u00f3n y placas madre necesarias para extraer el m\u00e1ximo rendimiento de otros chips de gama alta. Mientras tanto, Intel parece totalmente incapaz de contrarrestar la <a href=\"https:\/\/mastertrend.info\/ejecutar-un-modelo-de-ia-en-xbox-360\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"1673\">tecnolog\u00eda<\/a> 3D V-Cache de AMD, incluso despu\u00e9s de dos a\u00f1os y medio y tres generaciones de chips, desde que debut\u00f3 con el ahora legendario Ryzen 7 5800X3D. \ud83d\udd0d<\/p>\n<p>Vamos a echar un vistazo a la tecnolog\u00eda, y luego pasemos a los sorprendentemente buenos benchmarks de gaming. \ud83d\udcc8<\/p>\n<h2>\ud83d\udcbb Precio y Especificaciones del AMD Ryzen 7 9800X3D<\/h2>\n<p>El <em>Ryzen 7 9800X3D<\/em> cuenta con la <a href=\"https:\/\/mastertrend.info\/arte-digital-generado-por-ia\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"2851\">innovadora<\/a> microarquitectura Zen 5. Descubr\u00ed m\u00e1s sobre esta tecnolog\u00eda aqu\u00ed. \ud83e\uddd0 Este procesador es compatible con las placas madre AM5, y finalmente los socios de AMD tienen disponibles en el mercado los modelos <a class=\"wpil_keyword_link\" href=\"https:\/\/mastertrend.info\/breath-of-the-wild\/\" target=\"_blank\"  rel=\"noopener\" title=\"Breath of the Wild: La revoluci\u00f3n que cambi\u00f3 los mundos abiertos \ud83d\ude80\ud83c\udfae\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"15904\">X870E<\/a>. \ud83c\udf89<\/p>\n<p>&nbsp;<\/p>\n<div id=\"slice-container-table-X8gKaYYfDhupCfLRQKe8j4-PYiluNTD0HRLdKeA0T25eClCxb76bPNv\" class=\"slice-container table-wrapper table-X8gKaYYfDhupCfLRQKe8j4-PYiluNTD0HRLdKeA0T25eClCxb76bPNv slice-container-table\">\n<div class=\"table__container\">\n<table class=\"table__wrapper table__wrapper--inbodyContent table__wrapper--sticky table__wrapper--divider\">\n<caption class=\"table__caption table__caption--top table__caption--left\">AMD Ryzen 7 9800X3D \u2014 Pricing and Specifications<\/caption>\n<thead class=\"table__head\">\n<tr class=\"table__head__row\">\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">CPU<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Street (MSRP)<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Arch<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Cores \/ Threads (P+E)<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">P-Core Base \/ Boost Clock (GHz)<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">E-Core Base \/ Boost Clock (GHz)<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Cache (L2\/L3)<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">TDP \/ PBP or MTP<\/th>\n<th class=\"table__head__heading table__head__heading--left\" colspan=\"1\">Memory<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"table__body\">\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 9 7950X3D<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$599 ($699)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 4 X3D<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">16 \/ 32<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.2 \/ 5.7<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">\u2014<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">144MB (16+128)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">120W \/ 162W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5200<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 9 9950X<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$599 ($599)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">16 \/ 32<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.3 \/ 5.7<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">\u2014<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">80MB (16+64)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">170W \/ 230W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Core Ultra 9 285K<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$589<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Arrow Lake<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">24 \/ 24 (8+16)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.7 \/ 5.7<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.2 \/ 4.6<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">76MB (40+36)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">125W \/ 250W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">CUDIMM DDR5-6400 \/ DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Core i9-14900K \/ KF<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$445 K \/ $442 KF<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Raptor Lake Refresh<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">24 \/ 32 (8+16)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.2 \/ 6.0<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">&lt;2.4 \/ 4.4<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">68MB (32+36)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">125W \/ 253W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR4-3200 \/ DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 9 7900X3D<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$579 ($599)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 4 X3D<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">12 \/ 24<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.4 \/ 5.6<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">\u2014<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">140MB (12+128)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">120W \/ 162W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5200<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>Ryzen 7 9800X3D<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>$480<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>Zen 5 X3D<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>8 \/ 16<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>4.7 \/ 5.2<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">\u2014<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>104MB (8+96)<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>120W \/ 162W<\/strong><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><strong>DDR5-5600<\/strong><\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 7 7800X3D<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$476 ($449)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 4 X3D<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">8 \/ 16<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.2 \/ 5.0<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">\u2014<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">104MB (8+96)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">120W \/ 162W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5200<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 9 9900X<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$429 ($469)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">12 \/ 24<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.4 \/ 5.6<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">\u2014<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">76MB (12+64)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">120W \/ 162W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Core Ultra 7 265K \/ KF<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$394 \/ $379<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Arrow Lake<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">20 \/ 20 (8+12<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.9 \/ 5.5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.3 \/ 4.6<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">66MB (36+30)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">125W \/ 250W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">CUDIMM DDR5-6400 \/ DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Core i7-14700K \/ KF<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$354 K \/ $327 KF<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Raptor Lake Refresh<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">20 \/ 28 (8+12)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.4 \/ 5.6<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">2.5 \/ 4.3<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">61MB (28+33)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">125W \/ 253W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR4-3200 \/ DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Core i5-14600K \/ KF<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$256 K \/ $229 KF<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Raptor Lake Refresh<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">14 \/ 20 (6+8)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.5 \/ 5.3<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">2.6 \/ 4.0<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">44MB (20+24)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">125W \/ 181W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR4-3200 \/ DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 7 9700X<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$326 ($329)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">8 \/ 16<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.8 \/ 5.5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">\u2014<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">40MB (8+32)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">65W \/ 88W \/ 105W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Core Ultra 5 245K \/ KF<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$309 \/ $294<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Arrow Lake<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">14 \/ 14 (6+8)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.2 \/ 5.2<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.6 \/ 4.6<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">50MB (26+24)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">125W \/ 250W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">CUDIMM DDR5-6400 \/ DDR5-5600<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 5 9600X<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">$249 ($249)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Zen 5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">6 \/ 12<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">3.9 \/ 5.4<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">\u2014<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">38MB (6+32)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">65W \/ 88W \/ 105W<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5-5600<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>El Ryzen 7 9800X3D de ocho n\u00facleos y 16 hilos debuta a un precio de $480, con una diferencia de $30 sobre el precio de lanzamiento del Ryzen 7 7800X3D. \ud83d\udcb0 El 9800X3D cuenta con un TDP de 120W y ofrece frecuencias base 500 MHz m\u00e1s altas y aumentos de 200 MHz m\u00e1s que la generaci\u00f3n anterior, el Ryzen 7 7800X3D con <a href=\"https:\/\/mastertrend.info\/razer-presenta-innovaciones-en-videojuegos\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"1856\">tecnolog\u00eda<\/a> Zen 4. \ud83d\ude80<\/p>\n<p>El impulso de 5.2 GHz del 9800X3D es impresionante, pero queda por detr\u00e1s del comparable directo Zen 5, el Ryzen 7 9700X de ocho n\u00facleos, por 300 MHz. Sin embargo, AMD ha compensado con una frecuencia base 900 MHz m\u00e1s alta, permitiendo que el 9800X3D supere al 9700X en algunas cargas de trabajo con hilos, como ver\u00e1s en nuestros benchmarks en las siguientes p\u00e1ginas. \ud83d\udcca<\/p>\n<p>Al igual que los modelos de generaci\u00f3n anterior, el Ryzen 7 9800X3D no incluye un cooler. AMD recomienda un cooler l\u00edquido de al menos 240-280mm (o equivalente). \u2744\ufe0f El procesador mantiene la misma temperatura m\u00e1xima de 95\u00b0C (TjMax), pero el nuevo dise\u00f1o del chiplet de cach\u00e9 L3 permite que el chip opere a frecuencias m\u00e1s altas durante m\u00e1s tiempo (residencia de impulso mejorada), lo que se traduce en mayores ganancias de rendimiento dentro del mismo TDP. \ud83d\udcaa<\/p>\n<p>El Ryzen 7 9800X3D es completamente overclockeable: pod\u00e9s ajustar los n\u00facleos del CPU, las telas y la <a href=\"https:\/\/mastertrend.info\/camm2-nuevo-estandar-de-ram\/\" data-wpil-monitor-id=\"1122\" target=\"_blank\">memoria<\/a> a tu gusto. Aunque el overclocking basado en multiplicadores est\u00e1 disponible, como hemos visto con otros procesadores Zen 5, la mayor\u00eda de los usuarios con refrigeraci\u00f3n convencional estar\u00e1n mejor utilizando la funci\u00f3n de auto-overclocking <a href=\"https:\/\/mastertrend.info\/pbo-en-cpu-amd\/\" title=\"\u00a1PBO en CPU AMD: \u00a1Descubre el secreto para sacar el m\u00e1ximo provecho!\" target=\"_blank\" rel=\"noopener\"  data-wpil-monitor-id=\"34661\">Precision Boost Overdrive<\/a> (PBO). \ud83d\udd27 Tenemos pruebas exhaustivas con esta funci\u00f3n habilitada en las siguientes p\u00e1ginas. \ud83e\uddea<\/p>\n<p>Adem\u00e1s, AMD ha mejorado el soporte de memoria a DDR5-5600 desde el DDR5-5200 que se encontraba en el 7800X3D de la generaci\u00f3n anterior. \ud83d\udda5\ufe0f<\/p>\n<h2>Arquitectura del AMD Ryzen 7 9800X3D<\/h2>\n<div id=\"slice-container-imageGallery-X8gKaYYfDhupCfLRQKe8j4-uBQR3Q0mRdOTPPe2uIfRkO8ZCGkht7ii\" class=\"slice-container imageGallery-wrapper imageGallery-X8gKaYYfDhupCfLRQKe8j4-uBQR3Q0mRdOTPPe2uIfRkO8ZCGkht7ii slice-container-imageGallery\">\n<div class=\"inline-gallery first-slide-only\" data-hydrate=\"true\">\n<p><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" alt=\"AMD EPYC Milan-X\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952027_302_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" alt=\"AMD EPYC Milan-X\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952027_302_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952027_460_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" alt=\"Ryzen 7 5800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952027_460_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952027_377_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" alt=\"Ryzen 7 5800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952027_377_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952027_352_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" alt=\"Ryzen 7 5800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952027_352_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952028_351_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" alt=\"Ryzen 7 5800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952028_351_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952028_538_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" alt=\"Ryzen 7 5800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952028_538_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>En las ilustraciones de arriba, pod\u00e9s ver el enfoque original de AMD con su <a href=\"https:\/\/mastertrend.info\/como-deshabilitar-hyper-v-en-windows-11\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"2369\">tecnolog\u00eda<\/a> 3D V-Cache. Con dise\u00f1os anteriores que aprovecharon las arquitecturas Zen 3 y Zen 4, AMD apil\u00f3 un chiplet adicional de L3 SRAM directamente en el centro del chiplet de c\u00e1lculo (CCD) para aislarlo de los n\u00facleos que generan calor. \ud83d\udcca Hemos cubierto los detalles de la primera generaci\u00f3n de esta <a href=\"https:\/\/mastertrend.info\/alternativas-a-btscene\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"2497\">tecnolog\u00eda<\/a> [aqu\u00ed](#). AMD utiliz\u00f3 tecnolog\u00eda de uni\u00f3n h\u00edbrida para conectar el chiplet de cach\u00e9 al chip de c\u00e1lculo subyacente. Esto increment\u00f3 la capacidad de cach\u00e9 a 96MB, mejorando el rendimiento en aplicaciones sensibles a la latencia, como los videojuegos. \ud83c\udfae<\/p>\n<p>AMD coloc\u00f3 el chiplet y varias piezas de silicio estructural sobre el chip de c\u00e1lculo, pero como demostramos con pruebas de estrangulamiento t\u00e9rmico del <a href=\"https:\/\/mastertrend.info\/seguridad-pluton-de-microsoft\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"687\">procesador Ryzen<\/a> 9 7950X3D, el chiplet de cach\u00e9 y las l\u00e1minas de silicio estructural actuaron como una manta t\u00e9rmica que obstaculiz\u00f3 la transferencia de calor eficaz, esencialmente atrapando el calor residual. \ud83c\udf21\ufe0f Como resultado, AMD limit\u00f3 el voltaje y el rango de frecuencia efectivos del chip equipado con 3D V-Cache para controlar la generaci\u00f3n de calor. En pocas palabras, el chip se calentaba demasiado y, por lo tanto, ten\u00eda que funcionar m\u00e1s lento. \ud83d\udc22<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"inline-gallery first-slide-only\" data-hydrate=\"true\">\n<div id=\"slice-container-imageGallery-X8gKaYYfDhupCfLRQKe8j4-dXGbsiVR4hry1oeFYknF6iZ61x0ujSx2\" class=\"slice-container imageGallery-wrapper imageGallery-X8gKaYYfDhupCfLRQKe8j4-dXGbsiVR4hry1oeFYknF6iZ61x0ujSx2 slice-container-imageGallery\">\n<div class=\"inline-gallery first-slide-only\" data-hydrate=\"true\">\n<p><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952029_704_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" alt=\"Ryzen 7 9800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952029_704_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.jpg\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.png\" alt=\"Ryzen 7 9800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.png\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952029_380_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.png\" alt=\"Ryzen 7 9800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952029_380_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.png\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"> AMD ha colocado ahora el chiplet de cach\u00e9 debajo del dado para aliviar los desaf\u00edos t\u00e9rmicos, ubicando el dado de c\u00f3mputo m\u00e1s cerca del material de interfaz t\u00e9rmica, IHS, y eventualmente del cooler del CPU. Esto mejora la cantidad de rendimiento <a href=\"https:\/\/mastertrend.info\/windows-11-tarda-en-eliminar-archivos\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"208\">de c\u00f3mputo<\/a> que AMD puede extraer del sobre de 120W TDP, y tambi\u00e9n mejora la residencia\/duraci\u00f3n de impulso. Sin embargo, esto trae un nuevo conjunto de desaf\u00edos \u2014 este dise\u00f1o requiere que AMD enrute la energ\u00eda y las se\u00f1ales TSV de todo el chip a trav\u00e9s del chiplet de cach\u00e9 L3 subyacente. \ud83d\udd25\ud83d\udcbb<\/p>\n<p>El nuevo chiplet de cach\u00e9 L3 est\u00e1 basado en el mismo proceso de nodo optimizado para SRAM de 7nm que AMD utiliz\u00f3 en las dos generaciones anteriores de tecnolog\u00eda 3D V-Cache, en una t\u00e9cnica que AMD ahora denomina su tecnolog\u00eda de <em>\u00abSegunda Generaci\u00f3n 3D V-Cache\u00bb<\/em> (una elecci\u00f3n de marca un poco extra\u00f1a, ya que en realidad es la tercera refinaci\u00f3n de la tecnolog\u00eda). Como antes, AMD adelgaza tanto el chiplet de cach\u00e9 L3 como el dado de c\u00f3mputo de 4nm (N4P) para cumplir con los requisitos est\u00e1ndar de altura Z del paquete del procesador. \ud83d\udcbe\ud83d\udd27<\/p>\n<p>AMD utiliza la misma uni\u00f3n h\u00edbrida de cobre a cobre con un paso de protuberancia de 9 micrones para unir los dos dados. El chiplet ahora abarca toda la parte inferior del dado de c\u00f3mputo, eliminando as\u00ed la necesidad de las cu\u00f1as de silicona estructural. AMD no est\u00e1 compartiendo el tama\u00f1o del chiplet de cach\u00e9 L3 ni la densidad de transistores, pero el dado de c\u00f3mputo mide 70.6 mm\u00b2, por lo que es seguro apostar que ese tambi\u00e9n es el tama\u00f1o del chiplet de cach\u00e9.<\/p>\n<p>Esto es mucho m\u00e1s grande que el chiplet de cach\u00e9 L3 de 36 mm\u00b2 utilizado para los modelos Zen 4 X3D, a pesar del uso del mismo nodo de proceso y la misma capacidad de 64MB de L3. AMD probablemente tiene mucho silicio &#8216;vac\u00edo' en el chiplet de cach\u00e9 que est\u00e1 simplemente all\u00ed para soporte estructural, sin la necesidad de agregar cu\u00f1as separadas. \ud83d\udee0\ufe0f\ud83d\udccf<\/p>\n<div id=\"slice-container-imageGallery-X8gKaYYfDhupCfLRQKe8j4-7cDTdFqAnL2VPUE0G5DwHaNrA0Z2eZfP\" class=\"slice-container imageGallery-wrapper imageGallery-X8gKaYYfDhupCfLRQKe8j4-7cDTdFqAnL2VPUE0G5DwHaNrA0Z2eZfP slice-container-imageGallery\">\n<div class=\"inline-gallery first-slide-only\" data-hydrate=\"true\">\n<p><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952030_211_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.png\" alt=\"AMD Ryzen 7 9800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952030_211_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.png\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"><img decoding=\"async\" class=\"image-wrapped__image image__image\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952030_499_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.png\" alt=\"AMD Ryzen 7 9800X3D\" data-normal=\"https:\/\/vanilla.futurecdn.net\/cyclingnews\/media\/img\/missing-image.svg\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1730952030_499_Revision-del-AMD-Ryzen-7-9800X3D-Desempeno-Gaming-Devastador.png\" data-pin-nopin=\"true\" data-slice-image=\"true\" title=\"\"> <span class=\"caption-credit__credit\">(Image credit: Tom's Hardware)<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"slice-container-table-X8gKaYYfDhupCfLRQKe8j4-1h9S3GrTKorxKvcl8Wv2xJ33lQzq0XaX\" class=\"slice-container table-wrapper table-X8gKaYYfDhupCfLRQKe8j4-1h9S3GrTKorxKvcl8Wv2xJ33lQzq0XaX slice-container-table\">\n<div class=\"table__container\">\n<table class=\"table__wrapper table__wrapper--inbodyContent table__wrapper--sticky table__wrapper--divider\">\n<caption class=\"table__caption table__caption--top table__caption--left\">3D V-Cache Technology<\/caption>\n<tbody class=\"table__body\">\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\"><span class=\"sr-only\">Row 0 &#8211; Cell 0 <\/span><\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">\u00abNew\u00bb 2nd-Gen 7nm 3D V-Cache Die<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">2nd-Gen 7nm 3D V-Cache Die<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">First-Gen 7nm 3D V-Cache Die<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4nm Zen 5 Core Complex Die (CCD)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">5nm Zen 4 Core Complex Die (CCD)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">7nm Zen 3 Core Complex Die (CCD)<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Size<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">36mm^2<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">36mm^2<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">41mm^2<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">70.6 mm^2<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">66.3 mm^2<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">80.7mm^2<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Transistor Count<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">?<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">~4.7 Billion<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.7 Billion<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">8.6 billion<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">6.57 Billion<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">4.15 Billion<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">MTr\/mm^2 (Transistor Density)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">?<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">~130.6 Million<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">~114.6 Million<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">121.81 MTr\/mm^2<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">~99 Million<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">~51.4 Million<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>\ud83c\udf1f Naturalmente, AMD tiene que alimentar m\u00e1s energ\u00eda y se\u00f1al a trav\u00e9s de los TSVs en el chiplet de cach\u00e9 L3, que ahora act\u00faa como un tipo de interposer, hasta el die de computaci\u00f3n. \ud83d\udca1 AMD menciona que los TSVs de energ\u00eda est\u00e1n distribuidos a lo largo del die de SRAM para alimentar al die de computaci\u00f3n que se encuentra arriba. \ud83d\udd0b Los TSVs de energ\u00eda adicionales se distribuyen en \u00e1reas que no se usan para otras funciones (presumiblemente como m\u00e1s almacenamiento de cach\u00e9), lo que deber\u00eda al menos en parte explicar el tama\u00f1o m\u00e1s grande. \ud83d\udcc8<\/p>\n<p>&nbsp;<\/p>\n<div id=\"slice-container-table-X8gKaYYfDhupCfLRQKe8j4-7qY0xmDBfyfvsFAMJHjtpr1fGA0R0eiN\" class=\"slice-container table-wrapper table-X8gKaYYfDhupCfLRQKe8j4-7qY0xmDBfyfvsFAMJHjtpr1fGA0R0eiN slice-container-table\">\n<div class=\"table__container\">\n<table class=\"table__wrapper table__wrapper--inbodyContent table__wrapper--sticky table__wrapper--divider\">\n<caption class=\"table__caption table__caption--top table__caption--left\">AIDA L3 Cache Latency Measurements \u2014 Ryzen 7 9800X3D<\/caption>\n<tbody class=\"table__body\">\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Memory Latency &#8211; Tom's Hardware<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">DDR5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">CUDIMM DDR5<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">L3 Latency<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 7 9800X3D<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">78.5 ns (DDR5-6000)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">n\/a<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">13.2ns<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 7 7800X3D<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">73.4 ns (DDR5-6000)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">n\/a<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">12.8 ns<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Ryzen 7 9700X<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">69.4 ns (DDR5-6000)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">n\/a<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">11.3 ns<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Core Ultra 9 285K<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">94.1 ns (DDR5-5600)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">91.9 ns<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">16.6 \/ 15.8 ns<\/td>\n<\/tr>\n<tr class=\"table__body__row\">\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">Core i9-14900K<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">79.1 ns (DDR5-5600)<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">N\/A<\/td>\n<td class=\"table_body__data\" style=\"text-align: left;\" colspan=\"1\">21.8 ns<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>AMD menciona que los accesos al <strong>chiplet<\/strong> de cach\u00e9 L3 incurren en la misma penalizaci\u00f3n de cuatro ciclos que la generaci\u00f3n anterior. \ud83d\udd52<\/p>\n<p>Hemos medido un aumento en la latencia L3 de menos de un nanosegundo en comparaci\u00f3n con la generaci\u00f3n anterior equipada con <strong>3D V-Cache<\/strong>, como el Ryzen 7 7800X3D, lo cual se encuentra dentro de la variabilidad esperada. \ud83d\udcca<\/p>\n<p>AMD asegura que el ancho de banda entre el n\u00facleo de procesamiento y el chiplet L3 es similar al de la generaci\u00f3n anterior, con 2.5 TB\/s, aunque el ancho de banda var\u00eda con las velocidades de reloj. \ud83d\udcc8<\/p>\n<p>Ahora, los accesos tanto a la memoria principal como a I\/O deben pasar por el chiplet de cach\u00e9 L3. Como se puede observar en las mediciones anteriores, hay un marcado aumento en la latencia DDR5 en comparaci\u00f3n con el est\u00e1ndar Ryzen 7 9700X y el Ryzen 7 7800X3D. \ud83d\ude80<\/p>\n<p>AMD afirma que no hay aumento en la latencia de I\/O debido al paso por el chiplet de cach\u00e9. \ud83d\udee1\ufe0f Estamos buscando m\u00e1s detalles al respecto. Naturalmente, cualquier incremento en la latencia de memoria es indeseable. Sin embargo, esperamos que esto tenga un impacto m\u00ednimo en el rendimiento general gracias a la mayor cantidad de cach\u00e9 L3 que minimiza los accesos a la memoria principal en ciertos escenarios. \ud83d\udd0d<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>AMD Ryzen 7 9800X3D Review: Devastating Gaming Performance \ud83c\udfae\ud83d\udd25<\/p>","protected":false},"author":1,"featured_media":25102,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","iawp_total_views":75,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":""},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[74],"tags":[1445,1616],"class_list":["post-25101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","tag-evergreencontent","tag-ryzen"],"_links":{"self":[{"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/posts\/25101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/comments?post=25101"}],"version-history":[{"count":23,"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/posts\/25101\/revisions"}],"predecessor-version":[{"id":110111,"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/posts\/25101\/revisions\/110111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/media\/25102"}],"wp:attachment":[{"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/media?parent=25101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/categories?post=25101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastertrend.info\/en\/wp-json\/wp\/v2\/tags?post=25101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}