{"id":26750,"date":"2024-12-01T00:00:00","date_gmt":"2024-12-01T03:00:00","guid":{"rendered":"https:\/\/mastertrend.info\/?p=26750"},"modified":"2026-04-28T14:50:41","modified_gmt":"2026-04-28T17:50:41","slug":"bloquear-sites-2","status":"publish","type":"post","link":"https:\/\/mastertrend.info\/pt\/bloquear-sitios-web\/","title":{"rendered":"Guia para bloquear sites no Google Chrome"},"content":{"rendered":"<h2>Como bloquear sites no navegador Google Chrome.<\/h2>\n<div>\n<p>O Google Chrome poderia ser considerado o rei dos navegadores, por ser um dos mais populares e completos. Lidar com v\u00e1rios aspectos da navega\u00e7\u00e3o em sites, armazenamento de dados, downloads, etc. \u00e9 muito f\u00e1cil no Chrome. \ud83d\udc51<\/p>\n<p>Sejamos sinceros, h\u00e1 momentos em que queremos bloquear certos sites. Esses sites podem ser de diferentes tipos, como adultos, spam ou simplesmente uma perda de tempo. Por padr\u00e3o, o Chrome n\u00e3o permite <a class=\"wpil_keyword_link\" title=\"Com que frequ\u00eancia voc\u00ea deve desligar o telefone?\" href=\"https:\/\/mastertrend.info\/pt\/voce-deveria-desligar-seu-telefone\/\" target=\"_blank\" rel=\"noopener\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"7082\">bloquear sites<\/a>, mas existem algumas maneiras de fazer isso. \ud83d\udeab<\/p>\n<p>Ent\u00e3o, neste artigo, decidimos compartilhar as melhores formas de bloquear qualquer site no Google <a href=\"https:\/\/mastertrend.info\/pt\/erro-err_cache_miss\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"1329\">Cromo<\/a>. Vamos come\u00e7ar! \ud83d\ude80<\/p>\n<h2><span id=\"Block_Website_from_your_computer\"><strong>Bloqueie sites do seu computador<\/strong><\/span><\/h2>\n<p>Uma das melhores maneiras de bloquear um site espec\u00edfico \u00e9 editando o arquivo hosts. Aqui mostramos como bloquear sites usando o arquivo Hosts em <a href=\"https:\/\/mastertrend.info\/pt\/categoria\/windows\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"2295\">Windows<\/a>.<\/p>\n<p>1. Abra o Explorador de Arquivos e <a href=\"https:\/\/mastertrend.info\/pt\/desligamento-inesperado-do-microsoft-edge\/\" data-wpil-monitor-id=\"604\" target=\"_blank\">navegue at\u00e9 a pasta do Windows<\/a><strong> &gt; System32 &gt; drivers &gt; etc.<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-156847\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"clique duas vezes na pasta etc\" width=\"640\" height=\"327\" data-lazy-=\"\" title=\"\"><\/p>\n<p>2. Clique no bot\u00e3o visualizar na barra superior e selecione <strong>Mostrar &gt; Elementos Ocultos<\/strong>.<\/p>\n<p>3. Clique duas vezes no arquivo <strong>anfitri\u00f5es<\/strong> e selecione Bloco de notas para abri-lo.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-156844\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547009_595_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"selecione Bloco de Notas\" width=\"640\" height=\"516\" data-lazy-=\"\" title=\"\"><\/p>\n<p>4. <a href=\"https:\/\/mastertrend.info\/pt\/nenhum-dado-disponivel-no-facebook\/\" data-wpil-monitor-id=\"601\" target=\"_blank\">Digamos que voc\u00ea queira bloquear o facebook.com<\/a>. Para fazer isso, adicione uma linha ao final do arquivo hosts. A linha que voc\u00ea precisa adicionar \u00e9:<\/p>\n<pre><strong>0.0.0.0 facebook.com<\/strong><\/pre>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-156843\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547010_263_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"0.0.0.0 facebook.com\" width=\"600\" height=\"380\" data-lazy-=\"\" title=\"\"><\/p>\n<p>5. Quando terminar, clique em <strong>Arquivo &gt; Salvar<\/strong> para salvar o arquivo hosts.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-156842\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547010_378_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"Clique no bot\u00e3o Arquivo e selecione a op\u00e7\u00e3o &#039;Salvar&#039;\" width=\"600\" height=\"382\" data-lazy-=\"\" title=\"\"><\/p>\n<p>6. Voc\u00ea pode adicionar quantas p\u00e1ginas da web desejar ao arquivo hosts. Certifique-se de que o endere\u00e7o da web no arquivo <strong>aparece depois de 0.0.0.0<\/strong>.<\/p>\n<p>7. Para desbloquear o site, exclua a linha que voc\u00ea adicionou e salve o arquivo ou voc\u00ea pode adicionar <strong>#<\/strong> no in\u00edcio da linha para converter a sintaxe em um coment\u00e1rio, que ir\u00e1 desbloquear o site. \ud83d\ude4c<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-156841\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547010_698_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"exclua a linha que voc\u00ea adicionou\" width=\"640\" height=\"435\" data-lazy-=\"\" title=\"\"><\/p>\n<p>Voc\u00ea pode bloquear sites no seu computador usando o arquivo hosts. Os sites que voc\u00ea bloquear n\u00e3o ser\u00e3o carregados em nenhum navegador da web. \ud83d\udd12<\/p>\n<h2><span id=\"Block_Websites_using_Firewall_on_Windows_11\"><strong>Bloqueie sites usando o Firewall do Windows 11<\/strong><\/span><\/h2>\n<p>Voc\u00ea tamb\u00e9m pode usar o Firewall do Windows 11 para bloquear sites no seu computador. <a title=\"Recursos de IA no Chrome \ud83d\udd25: transforme sua navega\u00e7\u00e3o\" href=\"https:\/\/mastertrend.info\/pt\/recursos-de-ia-no-chrome\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"5023\">Navegador Chrome<\/a>. Voc\u00ea s\u00f3 precisa definir uma regra de firewall para bloquear sites. \ud83d\udea7<\/p>\n<p>A vantagem desse m\u00e9todo \u00e9 que voc\u00ea pode adicionar quantos sites quiser \u00e0 lista de bloqueio.<\/p>\n<h2><span id=\"Block_Website_Using_Block_Site_Extension\"><strong>Bloquear sites usando a extens\u00e3o Block Site<\/strong><\/span><\/h2>\n<p>\u00c9 um dos melhores bloqueadores de sites para Chrome. A extens\u00e3o ajuda os usu\u00e1rios a <a href=\"https:\/\/mastertrend.info\/pt\/como-verificar-a-temperatura-do-seu-processador\/\" data-wpil-monitor-id=\"602\" target=\"_blank\">manter<\/a> focado bloqueando sites que distraem. \ud83d\uded1<\/p>\n<p>Com Block Site, voc\u00ea pode bloquear facilmente qualquer site que distraia ou seja prejudicial. Aqui mostramos como usar a extens\u00e3o Block Site para bloquear determinados sites no Chrome.<\/p>\n<p>1. Baixe e <strong>instale a extens\u00e3o Block Site do Google Chrome<\/strong> a partir daqui.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-81382\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547010_996_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"instale a extens\u00e3o Block Site do Google Chrome\" width=\"608\" height=\"347\" data-lazy-=\"\" title=\"\"><\/p>\n<p>2. Ap\u00f3s o download, o navegador mostrar\u00e1 um pop-up. Clique <strong>Adicionar extens\u00e3o<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-81383\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547010_807_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"Clique em &#039;Adicionar extens\u00e3o&#039;\" width=\"613\" height=\"318\" data-lazy-=\"\" title=\"\"><\/p>\n<p>3. Depois de adicionado, voc\u00ea ver\u00e1 o \u00edcone Bloquear Site.<\/p>\n<p>4. Agora visite o site que deseja bloquear. Clique no \u00edcone e selecione <strong>Bloquear este site<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-81381\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547010_565_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"Bloquear este site\" width=\"598\" height=\"269\" data-lazy-=\"\" title=\"\"><\/p>\n<p>5. Para desbloquear o site, clique em <strong>Editar lista de sites bloqueados<\/strong>. Cada um dos seus sites bloqueados ter\u00e1 um <strong>menos<\/strong>. Clique no \u00edcone para desbloquear o site. \ud83d\udd13<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-81380 size-full\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547010_79_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"Para desbloquear sites, remova URLs das configura\u00e7\u00f5es de \u2018Bloquear site\u2019\" width=\"800\" height=\"238\" data-lazy-=\"\" title=\"\"><\/p>\n<p>\u00c9 assim que voc\u00ea pode usar a extens\u00e3o Block Site para bloquear determinados sites no navegador Google Chrome. \ud83c\udf10<\/p>\n<h2><span id=\"Other_Chrome_Extensions_to_Block_Website\"><strong>Outras extens\u00f5es do Chrome para bloquear sites<\/strong><\/span><\/h2>\n<p>Existem muitas <a class=\"wpil_keyword_link\" title=\"Senhas do Google Chrome: Resolva o problema facilmente agora! \u26a1\ufe0f\ud83d\udd27\" href=\"https:\/\/mastertrend.info\/pt\/senhas-do-google-chrome-2\/\" target=\"_blank\" rel=\"noopener\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"7081\">extens\u00f5es do Google<\/a> Chrome dispon\u00edveis na loja para bloquear sites. Essas extens\u00f5es s\u00e3o muito f\u00e1ceis de configurar. Basta instal\u00e1-las no seu <a href=\"https:\/\/mastertrend.info\/pt\/chrome-nao-carrega-paginas-no-android\/\" data-wpil-monitor-id=\"603\" target=\"_blank\">Navegador Chrome<\/a> e adicione os URLs \u00e0 lista de bloqueios. \ud83d\udd0d<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-92708 size-full\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547011_473_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"Mantenha o foco\" width=\"719\" height=\"458\" data-lazy-=\"\" title=\"\"><\/p>\n<p>\u00c9 uma extens\u00e3o de <a href=\"https:\/\/mastertrend.info\/pt\/como-baixar-videos-incorporados\/\" data-wpil-monitor-id=\"605\" target=\"_blank\">produtividade<\/a> para Google Chrome que ajuda voc\u00ea a manter o foco no trabalho, limitando o tempo que voc\u00ea pode gastar em sites que desperdi\u00e7am tempo.<\/p>\n<p>Voc\u00ea pode adicionar sites \u00e0 lista de bloqueados; Eles n\u00e3o estar\u00e3o acess\u00edveis durante o resto do dia. \u23f3<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-205191\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547011_661_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"FocusGuard\" width=\"600\" height=\"395\" data-lazy-=\"\" title=\"\"><\/p>\n<p>FocusGuard \u00e9 uma extens\u00e3o do Chrome que permite que voc\u00ea se concentre em trabalhos importantes e bloqueie distra\u00e7\u00f5es.<\/p>\n<p>Basicamente, \u00e9 uma extens\u00e3o de bloqueio de sites que permite definir um limite de tempo para sites que distraem.<\/p>\n<p>Depois de atingir o limite, a extens\u00e3o bloqueia automaticamente o site. \/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547011_49_Como-blocker-sitios-web-en-el-navegador-Google-Chrome.jpg\u00bb alt=\u00bbBloqueador de sites (Beta)\u00bb largura=\u00bb 815\u2033 altura=\u00bb476\u2033 dados-pregui\u00e7osos-=\u00bb\u00bb \/&gt;<img decoding=\"async\" class=\"aligncenter wp-image-92706 size-full\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/11\/1732547011_49_Como-bloquear-sitios-web-en-el-navegador-Google-Chrome.jpg\" alt=\"Bloqueador de sites (Beta)\" width=\"815\" height=\"476\" title=\"\"><\/p>\n<p>Se voc\u00ea est\u00e1 procurando uma extens\u00e3o do Chrome para ajud\u00e1-lo a se concentrar no seu trabalho, o Bloqueador de sites (Beta) pode ser a melhor op\u00e7\u00e3o. \ud83d\udcbc<\/p>\n<p>Voc\u00ea sabia? O Website Blocker (Beta) permite aos usu\u00e1rios bloquear URLs, incluindo strings de texto espec\u00edficas. Al\u00e9m disso, tamb\u00e9m permite agendar um hor\u00e1rio para bloquear sites! \ud83d\udcc5<\/p>\n<p>Este guia foi sobre como bloquear sites no Google Chrome. Espero que este artigo tenha sido \u00fatil para voc\u00ea! Compartilhe isso com seus amigos. \ud83e\udd1d<\/p>\n<p><!-- CONTENT END 1 --><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Como bloquear sites no navegador Google Chrome, melhores maneiras de bloquear qualquer site no Google Chrome.<\/p>","protected":false},"author":1,"featured_media":26751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wpai_generated_summary":"","iawp_total_views":178,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"1","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":""},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[308],"tags":[1582,1639,1445],"class_list":["post-26750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","tag-browsertips","tag-ciberseguridad","tag-evergreencontent"],"_links":{"self":[{"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/posts\/26750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/comments?post=26750"}],"version-history":[{"count":0,"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/posts\/26750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/media\/26751"}],"wp:attachment":[{"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/media?parent=26750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/categories?post=26750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastertrend.info\/pt\/wp-json\/wp\/v2\/tags?post=26750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}