{"id":48524,"date":"2025-11-07T01:35:59","date_gmt":"2025-11-07T04:35:59","guid":{"rendered":"https:\/\/mastertrend.info\/?p=48524"},"modified":"2025-11-07T01:35:59","modified_gmt":"2025-11-07T04:35:59","slug":"%d1%83%d0%bb%d1%83%d1%87%d1%88%d0%b8%d1%82%d1%8c-%d0%be%d1%80%d1%83%d0%b6%d0%b8%d0%b5-%d0%b8-%d1%89%d0%b8%d1%82%d1%8b","status":"publish","type":"post","link":"https:\/\/mastertrend.info\/ru\/mejorar-armas-y-escudos\/","title":{"rendered":"\u0423\u043b\u0443\u0447\u0448\u0430\u0439\u0442\u0435 \u043e\u0440\u0443\u0436\u0438\u0435 \u0438 \u0449\u0438\u0442\u044b \u27a1\ufe0f \u0421\u0435\u043a\u0440\u0435\u0442\u043d\u044b\u0435 \u043f\u0440\u0438\u0435\u043c\u044b \u0432 Doom The Dark Ages \u27a1"},"content":{"rendered":"<h2>Mejorar armas y escudos \u2694\ufe0f Domina los Santuarios Sentinel r\u00e1pido \ud83d\udca5<\/h2>\n<p class=\"my-2 [&+p]:mt-4 [&_strong:has(+br)]:inline-block [&_strong:has(+br)]:pb-2\">\ud83d\udd25\ud83d\udc80 \u00a1Prep\u00e1rate para dominar el caos en\u00a0<em>Doom The Dark Ages<\/em>! \ud83d\udca5 Tus armas y escudo no son solo herramientas de destrucci\u00f3n, sino piezas clave que pueden convertirte en una aut\u00e9ntica m\u00e1quina de guerra. \u2694\ufe0f Pero ojo: para desbloquear su verdadero poder, tendr\u00e1s que reunir toneladas de Oro, Rub\u00edes y Piedra Fantasma \ud83d\udcb0\ud83d\udc8e\ud83d\udc80\u2026 y saber d\u00f3nde invertirlos en los misteriosos Santuarios Sentinel. \ud83c\udfdb\ufe0f<\/p>\n<p class=\"my-2 [&+p]:mt-4 [&_strong:has(+br)]:inline-block [&_strong:has(+br)]:pb-2\">Algunas armas esconden mejoras dobles que puedes alternar para crear combinaciones devastadoras \u2699\ufe0f\ud83d\udd25 \u2014 \u00a1una aut\u00e9ntica locura estrat\u00e9gica para los fans del combate m\u00e1s brutal! \ud83d\ude08<\/p>\n<p class=\"my-2 [&+p]:mt-4 [&_strong:has(+br)]:inline-block [&_strong:has(+br)]:pb-2\">Si quieres gastar tus recursos con cabeza y avanzar como un verdadero Slayer, aqu\u00ed te dejo una gu\u00eda definitiva con las mejores mejoras, qu\u00e9 comprar primero y c\u00f3mo exprimir cada arma al m\u00e1ximo. \ud83d\ude80\ud83d\udcaa<\/p>\n<h2 id=\"mejores-mejoras-doom-dark-ages\">Las mejores mejoras en Doom The Dark Ages<\/h2>\n<figure class=\"van-image-figure inline-layout\"><picture><source type=\"image\/webp\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"Men\u00fa de mejoras en el santuario Sentinel de Doom The Dark Ages para armas y escudo\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" title=\"\"><\/picture><figcaption class=\"inline-layout\"><span class=\"credit\">(<a href=\"https:\/\/doom.bethesda.net\/pt-BR\/the-dark-ages\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"mentions\">Cr\u00e9dito imagen: Bethesda Softworks<\/a>)<\/span><\/figcaption><\/figure>\n<p>Para desbloquear mejoras en armas, cuerpo a cuerpo, escudo y runas en <strong>Doom The Dark Ages<\/strong>, necesitas recolectar Oro, Rub\u00edes y Piedras Fantasma y encontrar un Santuario Sentinel para comprar las mejoras. El juego ofrece suficientes recursos para desbloquear todo, pero si prefieres un progreso r\u00e1pido y sin mucha exploraci\u00f3n, enf\u00f3cate en mejoras que realmente potencien tu arsenal.<\/p>\n<figure class=\"van-image-figure inline-layout\"><picture><source type=\"image\/webp\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102527_934_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"Barras de oro necesarias para mejoras en Doom The Dark Ages en el suelo\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102527_934_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" title=\"\"><\/picture><figcaption class=\"inline-layout\"><span class=\"credit\">(Cr\u00e9dito imagen: Bethesda Softworks)<\/span><\/figcaption><\/figure>\n<ul>\n<li><strong>Mejoras para el escudo:<\/strong> El escudo te acompa\u00f1a siempre, por lo que mejorarlo completamente lo antes posible es clave. Las mejoras de <em>Represalia<\/em> y <em>Filo Extendio<\/em> son muy \u00fatiles, pero tu objetivo debe ser alcanzar <em>Maestro de la Hoja<\/em>, el nivel final.<\/li>\n<li><strong>Mejora incendiaria para la Escopeta de Combate:<\/strong> Permite incendiar demonios y hacer que suelten armadura, lo que es vital para mantenerte protegido. Las siguientes mejoras potencian a\u00fan m\u00e1s este efecto.<\/li>\n<li><strong>Mejora Coj\u00edn de Alfileres para Trituradora:<\/strong> Aunque la Trituradora no es la m\u00e1s destacada, esta mejora crea una explosi\u00f3n de metralla perfecta para eliminar grupos de enemigos en el inicio.<\/li>\n<li><strong>Mejoras para la Super Escopeta:<\/strong> Considerada la mejor arma del juego, vale la pena priorizar sus tres mejoras para maximizar da\u00f1o y efectividad.<\/li>\n<li><strong>Mejoras para el Mangual:<\/strong> Una mejora significativa respecto al Guantelete de Poder. Las mejoras <em>Condicionamiento<\/em> y <em>Ignici\u00f3n<\/em> son excelentes para generar y romper armadura.<\/li>\n<li><strong>Mejora Bendici\u00f3n Ancestral para Chainshot:<\/strong> Eliminar el tiempo de carga de la cadena es un avance crucial para atacar inmediatamente tras una parry, ideal para combos r\u00e1pidos y letales.<\/li>\n<\/ul>\n<p>Si una mejora no aparece en esta lista, no significa que sea in\u00fatil. Cada una aporta valor, y si tienes recursos, mejora lo que puedas para fortalecer a tu Doom Slayer. Explorar y recoger oro es fundamental para desbloquear todo sin problemas, \u00a1revisa nuestra gu\u00eda de consejos para Doom The Dark Ages para sacar m\u00e1ximo provecho!<\/p>\n<h2 id=\"mejores-combinaciones-armas-doom-dark-ages\">Mejores combinaciones de mejoras para armas en Doom The Dark Ages<\/h2>\n<figure class=\"van-image-figure inline-layout\"><picture><source type=\"image\/webp\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102527_526_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"Mejores mejoras para escudo Sierra en Doom The Dark Ages\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102527_526_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" title=\"\"><\/picture><figcaption class=\"inline-layout\"><span class=\"credit\">(Cr\u00e9dito imagen: Bethesda Softworks)<\/span><\/figcaption><\/figure>\n<div class=\"fancy-box\">\n<p>\u00bfD\u00f3nde se ubica el Dark Ages en la l\u00ednea de tiempo de Doom?<\/p>\n<div class=\"fancy_box_body\">\n<figure class=\"van-image-figure\"><picture><source type=\"image\/webp\" data-pin-nopin=\"true\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_902_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"El Slayer o Doomguy en Doom The Dark Ages\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_902_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" data-pin-nopin=\"true\" title=\"\"><\/picture><figcaption><span class=\"credit\">(Cr\u00e9dito imagen: Bethesda Softworks)<\/span><\/figcaption><\/figure>\n<p class=\"fancy-box__body-text\">\u00a1Descubre todo lo que necesitas saber sobre la ambientaci\u00f3n y lore de Doom The Dark Ages antes de jugar aqu\u00ed!<\/p>\n<p>El juego no lo explica claramente, pero para armas con dos mejoras en la misma fila, comprar una desbloquea ambas y t\u00fa eliges cu\u00e1l utilizar. Puedes cambiar libremente entre ellas desde el men\u00fa de dossiers del arma para experimentar distintas configuraciones.<\/p>\n<p>Algunas mejoras y combinaciones destacan m\u00e1s que otras. Aqu\u00ed tienes <a href=\"https:\/\/mastertrend.info\/armas-de-doom-the-dark-ages\/\" title=\"Armas de Doom The Dark Ages: 23 armas reveladas \u2694\ufe0f\ud83d\udd25\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"9772\">las m\u00e1s recomendadas para cada arma<\/a> en Doom The Dark Ages:<\/p>\n<h2 id=\"mejores-mejoras-escopeta-combate\">Mejores mejoras para la Escopeta de Combate en Doom The Dark Ages<\/h2>\n<figure class=\"van-image-figure inline-layout\"><picture><source type=\"image\/webp\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_669_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"Las mejores mejoras para la Escopeta de Combate en Doom The Dark Ages\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_669_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" title=\"\"><\/picture><figcaption class=\"inline-layout\"><span class=\"credit\">(Cr\u00e9dito imagen: Bethesda Softworks)<\/span><\/figcaption><\/figure>\n<ul>\n<li><strong>Smelt vs Blast:<\/strong>\n<ul>\n<li><strong>Smelt:<\/strong> Aumenta los \u00edtems de armadura que caen tras incendiar demonios, garantizando una fuente constante de armadura. <strong>Blast<\/strong> es \u00fatil temprano, pero <em>Smelt<\/em> brilla en las etapas avanzadas.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Tune Up vs Flare-Up:<\/strong>\n<ul>\n<li><strong>Flare-Up:<\/strong> La mejor opci\u00f3n para eliminar enemigos d\u00e9biles y obtener armadura sin complicaciones. <strong>Ignora Tune Up<\/strong>, no ofrece ventajas significativas.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"mejor-mejora-shredder\">Mejor mejora para la Trituradora en Doom The Dark Ages<\/h2>\n<figure class=\"van-image-figure inline-layout\"><picture><source type=\"image\/webp\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_587_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"Mejores mejoras para la Trituradora en Doom The Dark Ages\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_587_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" title=\"\"><\/picture><figcaption class=\"inline-layout\"><span class=\"credit\">(Cr\u00e9dito imagen: Bethesda Softworks)<\/span><\/figcaption><\/figure>\n<ul>\n<li><strong>Pincushion vs Ricochet:<\/strong>\n<ul>\n<li><strong>Pincushion:<\/strong> Prefiere esta mejora para desatar explosiones de metralla m\u00e1s poderosas y conservar tu escudo intacto. Adem\u00e1s, funciona mejor con la mejora <em>Barbed<\/em>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"mejor-mejora-impaler\">Mejor mejora para Impaler en Doom The Dark Ages<\/h2>\n<figure class=\"van-image-figure inline-layout\"><picture><source type=\"image\/webp\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_400_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"Mejores mejoras para Impaler en Doom The Dark Ages\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_400_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" title=\"\"><\/picture><figcaption class=\"inline-layout\"><span class=\"credit\">(Cr\u00e9dito imagen: Bethesda Softworks)<\/span><\/figcaption><\/figure>\n<ul>\n<li><strong>Salvage vs Chronospike:<\/strong>\n<ul>\n<li><strong>Salvage:<\/strong> Mayor da\u00f1o de impacto y \u00e1rea, perfecto para eliminar varios enemigos a la vez. <strong>Chronospike<\/strong> ralentiza el tiempo y ayuda en la punter\u00eda, aunque su da\u00f1o es menor.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"mejores-mejoras-plasma-accelerator\">Mejores mejoras para Plasma Accelerator en Doom The Dark Ages<\/h2>\n<figure class=\"van-image-figure inline-layout\"><picture><source type=\"image\/webp\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_834_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"Mejores mejoras para Plasma Accelerator en Doom The Dark Ages\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102528_834_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" title=\"\"><\/picture><figcaption class=\"inline-layout\"><span class=\"credit\">(Cr\u00e9dito imagen: Bethesda Softworks)<\/span><\/figcaption><\/figure>\n<ul>\n<li><strong>Stabilizer vs Modulator:<\/strong>\n<ul>\n<li><strong>Modulator:<\/strong> Mayor velocidad de disparo para infligir m\u00e1s da\u00f1o r\u00e1pido. <strong>No pierdas tiempo con Stabilizer.<\/strong><\/li>\n<\/ul>\n<\/li>\n<li><strong>Heatblast vs Mega Cell:<\/strong>\n<ul>\n<li><strong>Heatblast:<\/strong> Un potente ataque cargado que limpia grupos enemigos o da\u00f1a mucho a grandes demonios. <strong>Mega Cell<\/strong> es buena, pero mejor para usar con Cycler, si prefieres disparos constantes.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"mejor-mejora-ravager\">Mejor mejora para Ravager en Doom The Dark Ages<\/h2>\n<figure class=\"van-image-figure inline-layout\"><picture><source type=\"image\/webp\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102529_246_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"Mejores mejoras para Ravager en Doom The Dark Ages\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102529_246_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" title=\"\"><\/picture><figcaption class=\"inline-layout\"><span class=\"credit\">(Cr\u00e9dito imagen: Bethesda Softworks)<\/span><\/figcaption><\/figure>\n<ul>\n<li><strong>Ignition vs Slow Burn:<\/strong>\n<ul>\n<li><strong>Ignition:<\/strong> Acelera la tasa de fuego m\u00e1xima y elimina penalizaci\u00f3n de movimiento, aumentando el DPS y movilidad. <strong>Slow Burn tiene demasiadas desventajas.<\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h2 id=\"mejor-mejora-rocket-launcher\">Mejor mejora para el Lanzacohetes en Doom The Dark Ages<\/h2>\n<figure class=\"van-image-figure inline-layout\"><picture><source type=\"image\/webp\" \/><\/picture> <picture><img decoding=\"async\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102529_456_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" alt=\"Mejores mejoras para el Lanzacohetes en Doom The Dark Ages\" data-pin-media=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/05\/1747102529_456_Las-mejores-mejoras-para-tus-armas-y-escudo-en-Doom.jpg\" title=\"\"><\/picture><\/figure>\n<\/div>\n<\/div>\n<p><span class=\"credit\">(Cr\u00e9dito imagen: Bethesda Softworks)<\/span><\/p>\n<ul>\n<li><strong>Cooked vs Blood Sacrifice:<\/strong>\n<ul>\n<li><strong>Cooked:<\/strong> M\u00e1s seguro para potenciar el Lanzacohetes con parrys confiables. <strong>Blood Sacrifice<\/strong> ofrece mayor poder pero aumenta el da\u00f1o auto-infligido, requiere precauci\u00f3n.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><em>Si te falta algo de oro, intenta <a title=\"Pr\u00edncipe Azul la puerta del garaje: Desbloquea el secreto hoy \u26a1\ud83d\udd13\" href=\"https:\/\/mastertrend.info\/principe-azul-la-puerta-del-garaje\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"8732\">abrir la puerta<\/a><strong> de fuego en Hebeth<\/strong> o destruir todas las <strong>Estatuas de Lobo de Doom The Dark Ages<\/strong> para obtener materiales de mejora avanzados, adem\u00e1s de buscar las m\u00e1s desafiantes <strong>Piedras Fantasma en la Aguja de Nerathul<\/strong> para potenciar tus armas al m\u00e1ximo.<\/em><\/p>\n<p>\ud83d\udd25 \u00a1Potencia tu arsenal y domina Doom The Dark Ages! <a href=\"https:\/\/mastertrend.info\/doom-the-dark-ages-y-la-mejor-arma\/\" title=\"Doom The Dark Ages y la mejor arma \u00a1Descubre la Super Escopeta letal!\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"9771\">Descubre m\u00e1s gu\u00edas y tips<\/a> en nuestra p\u00e1gina y no olvides explorar todos los rincones para maximizar tu experiencia. \ud83d\udca5<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0423\u043b\u0443\u0447\u0448\u0435\u043d\u0438\u0435 \u043e\u0440\u0443\u0436\u0438\u044f \u0438 \u0449\u0438\u0442\u043e\u0432 \ud83d\udee1\ufe0f \u0432 Doom: The Dark Ages \u0434\u0430\u0451\u0442 \u0432\u0430\u043c \u043f\u043e\u043b\u043d\u0443\u044e \u0432\u043b\u0430\u0441\u0442\u044c: \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u0443\u0439\u0442\u0435 \u0441\u0432\u044f\u0442\u0438\u043b\u0438\u0449\u0430 \u0421\u0442\u0440\u0430\u0436\u0435\u0439 \u0438 \u043b\u0435\u0433\u043a\u043e \u0441\u043e\u0437\u0434\u0430\u0432\u0430\u0439\u0442\u0435 \u0441\u043c\u0435\u0440\u0442\u043e\u043d\u043e\u0441\u043d\u044b\u0435 \u043a\u043e\u043c\u0431\u043e \ud83d\udc80\ud83d\udd25<\/p>","protected":false},"author":1,"featured_media":83745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","iawp_total_views":34,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"1","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":""},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[329],"tags":[1445,1624,1657],"class_list":["post-48524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaming","tag-evergreencontent","tag-gamerlife","tag-videojuegos"],"_links":{"self":[{"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/posts\/48524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/comments?post=48524"}],"version-history":[{"count":0,"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/posts\/48524\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/media\/83745"}],"wp:attachment":[{"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/media?parent=48524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/categories?post=48524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastertrend.info\/ru\/wp-json\/wp\/v2\/tags?post=48524"}],"curies":[{"name":"WP","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}