{"id":32253,"date":"2025-05-11T22:29:05","date_gmt":"2025-05-12T01:29:05","guid":{"rendered":"https:\/\/mastertrend.info\/?p=32253"},"modified":"2025-12-15T21:49:38","modified_gmt":"2025-12-16T00:49:38","slug":"%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%97%e0%b8%b3%e0%b8%8b%e0%b9%89%e0%b8%b3%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%ad%e0%b8%b1%e0%b8%9b%e0%b9%80%e0%b8%94%e0%b8%95%e0%b8%9f","status":"publish","type":"post","link":"https:\/\/mastertrend.info\/th\/como-repetir-y-actualizar-campos-en-word\/","title":{"rendered":"\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e0b\u0e49\u0e33\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e1f\u0e34\u0e25\u0e14\u0e4c\u0e43\u0e19 Word \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e27\u0e25\u0e32 \u23f3\ud83d\udd25"},"content":{"rendered":"<h2>C\u00f3mo repetir y actualizar campos en Word \u00a1R\u00e1pido y f\u00e1cil! \u2728\ud83d\udd8a\ufe0f<\/h2>\n<p>Ya sea que est\u00e9s redactando un contrato, t\u00e9rminos y condiciones, o una carta de presentaci\u00f3n, \u00a1no pierdas tiempo repitiendo los mismos nombres y palabras en tu documento! En Microsoft Word, pod\u00e9s crear campos de texto que se repiten autom\u00e1ticamente, ahorr\u00e1ndote el trabajo de duplicar detalles manualmente. \ud83d\udd8a\ufe0f\u2728<\/p>\n<h2 id=\"step-1-create-a-document-property\">Paso 1: Crear una Propiedad del Documento<\/h2>\n<p>Las propiedades de los documentos en Microsoft Word son detalles sobre el archivo, conocidos tambi\u00e9n como metadato. Por ejemplo, un documento puede tener asignado un autor, un tema, una categor\u00eda o una empresa, y pod\u00e9s insertar estas propiedades en tu trabajo como campos de texto, o usarlas para buscar un documento en el <a class=\"wpil_keyword_link\" href=\"https:\/\/mastertrend.info\/monitor-negro-en-windows-11\/\" target=\"_blank\"  rel=\"noopener\" title=\"Monitor negro en Windows 11: Soluciona este fallo en minutos \ud83d\udee0\ufe0f\ud83d\udd25\" data-wpil-keyword-link=\"linked\"  data-wpil-monitor-id=\"34528\">Explorador de Windows<\/a>. \ud83d\uddc2\ufe0f<\/p>\n<p>Sin embargo, una de las formas en que uso la herramienta de propiedades de Word es para agregar un campo de texto repetido personalizado. \ud83d\udcbc<\/p>\n<p>En mi caso, estoy redactando un contrato de trabajo, as\u00ed que s\u00e9 que tendr\u00e9 que repetir el nombre de la empresa y el nombre del empleado. Tambi\u00e9n tengo claro que tendr\u00e9 que cambiar el nombre del empleado cada vez que ingrese alguien nuevo, y la herramienta de propiedades del documento me permite hacerlo sin tener que cambiarlos manualmente o usar la funci\u00f3n de Buscar y Reemplazar. \ud83d\udd04<\/p>\n<p>En la pesta\u00f1a Insertar de la cinta de opciones, hac\u00e9 clic en \u00abPartes R\u00e1pidas\u00bb y pas\u00e1 el mouse por encima de \u00abPropiedad del Documento.\u00bb Escane\u00e1 la lista de propiedades para ver si hay una categor\u00eda que funcione para el detalle repetido que quer\u00e9s agregar. Despu\u00e9s de escribir las primeras palabras del t\u00edtulo de mi contrato, har\u00e9 clic en \u00abEmpresa\u00bb para agregar un campo de empresa. \ud83c\udfe2<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"El men\u00fa de partes r\u00e1pidas en Microsoft Word, con la opci\u00f3n de Empresa seleccionada.\" width=\"750\" height=\"408\" title=\"\"><\/figure>\n<p>Si trabaj\u00e1s en una computadora de empresa, tu administrador ya podr\u00eda haber configurado el nombre de la empresa en tu paquete de Microsoft 365, lo que har\u00eda que el nombre de la empresa se insertara autom\u00e1ticamente. En mi caso, Word inserta un campo en blanco [Empresa] en mi documento, con los corchetes indicando que es un texto de marcador de posici\u00f3n que a\u00fan no ha sido modificado. \ud83d\udcc4<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428009_144_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"Un documento de Microsoft Word con la propiedad de documento de la empresa a\u00f1adida al t\u00edtulo.\" width=\"750\" height=\"197\" title=\"\"><\/figure>\n<p>Ahora es momento de agregar el campo del empleado. Dado que no hay una opci\u00f3n espec\u00edfica para esto en el men\u00fa desplegable de Partes R\u00e1pidas &gt; Propiedad del Documento, har\u00e9 clic en \u00abResumen.\u00bb \ud83d\udcdd<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428009_345_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"El men\u00fa de partes r\u00e1pidas en Microsoft Word, con la opci\u00f3n Resumen seleccionada.\" width=\"750\" height=\"373\" title=\"\"><\/figure>\n<p>Antes de escribir el nombre del empleado en este campo, quiero cambiar el nombre del campo de Resumen a Empleado. Para hacer esto, despu\u00e9s de seleccionar el campo de Resumen que acabo de agregar, har\u00e9 clic en \u00abPropiedades\u00bb en el grupo de Controles de la pesta\u00f1a Desarrollador. \ud83d\udee0\ufe0f<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428009_795_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"El campo Resumen est\u00e1 seleccionado en un documento de Word, y el icono de Propiedades en la pesta\u00f1a Desarrollador est\u00e1 destacado.\" width=\"750\" height=\"461\" title=\"\"><\/figure>\n<p>En el cuadro de di\u00e1logo Propiedades de Control de Contenido, cambi\u00e1 los campos de T\u00edtulo y Etiqueta para que coincidan con el tipo de dato que contendr\u00e1, y hac\u00e9 clic en \u00abAceptar.\u00bb \ud83d\udc4d<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428010_563_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"El cuadro de di\u00e1logo Propiedades de Control de Contenido en Microsoft Word, con los campos de T\u00edtulo y Etiqueta que contienen la palabra &#039;Empleado&#039;.\" width=\"750\" height=\"562\" title=\"\"><\/figure>\n<p>Ahora, puedo ver que mi campo de texto ha sido renombrado a \u00abEmpleado.\u00bb No necesito hacer esto para mi campo de Empresa, ya que es una propiedad de documento predeterminada que ya tiene el nombre correcto. \u2705<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428010_371_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"Un campo de texto de Microsoft Word llamado &#039;Empleado&#039;.\" width=\"750\" height=\"323\" title=\"\"><\/figure>\n<p>Finalmente, puedo hacer clic en cada uno de los dos campos que he agregado e insertar los detalles correctos. \ud83d\udc65<\/p>\n<h2 id=\"step-2-add-the-repeating-fields\">Paso 2: Agregar los Campos Repetidos<\/h2>\n<p>Ahora que configuraste tus campos de texto, es momento de duplicarlos en todo tu documento. \ud83d\udcdc<\/p>\n<p>Existen varias maneras de hacerlo, pero la mejor forma es seleccionar el campo con un solo clic y luego hacer clic en la pesta\u00f1a del nombre del campo. Sabr\u00e1s que seleccionaste correctamente el campo cuando adopte un fondo gris. \ud83d\uddb1\ufe0f<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428010_690_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"Un campo de documento en Microsoft Word est\u00e1 seleccionado, como se indica por el destacado gris sobre el texto.\" width=\"750\" height=\"301\" title=\"\"><\/figure>\n<p>A continuaci\u00f3n, presion\u00e1 Ctrl+C para copiar ese campo. \ud83d\udd04<\/p>\n<p>Ahora, con el cursor en la posici\u00f3n donde quieras duplicar ese campo, presion\u00e1 Ctrl+V. \ud83d\udccb<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428010_327_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"Un campo de propiedad de documento duplicado en un documento de Microsoft Word.\" width=\"750\" height=\"260\" title=\"\"><\/figure>\n<p>Fijate c\u00f3mo el campo y el texto que contiene se copian a esta ubicaci\u00f3n duplicada. Tambi\u00e9n, el campo de texto pegado adopta autom\u00e1ticamente el estilo de texto que estoy utilizando en ese p\u00e1rrafo, lo que significa que no tengo que usar la opci\u00f3n de Pegado Especial. \ud83d\udd8c\ufe0f<\/p>\n<p>Dado que mi documento contiene dos campos que quiero duplicar, abrir\u00e9 el panel del portapapeles haciendo clic en el \u00edcono en la esquina del grupo del portapapeles en la pesta\u00f1a de Inicio. Cuando selecciono cada uno de mis dos campos y presiono Ctrl+C, aparecer\u00e1n en este panel, lo que significa que puedo simplemente hacer clic en ellos cada vez que quiera agregarlos a mi contrato. \ud83d\udccb\u2728<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428010_208_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"El panel de portapapeles en Microsoft Word, que contiene &#039;Joe Bloggs&#039; y &#039;How-To Geek&#039;.\" width=\"750\" height=\"342\" title=\"\"><\/figure>\n<p>El portapapeles de Microsoft Office puede contener hasta 24 elementos, as\u00ed que esta es una t\u00e9cnica muy \u00fatil si est\u00e1s repitiendo muchos campos diferentes en tu documento. \ud83d\uddd2\ufe0f<\/p>\n<h2 id=\"step-3-change-the-contents-of-the-repeating-fields\">Paso 3: Cambiar el Contenido de los Campos Repetidos<\/h2>\n<p>Cuando hayas terminado de duplicar estos campos en todo tu documento, es momento de ver la magia suceder. \ud83c\udfa9\u2728<\/p>\n<p>Supongamos que quiero cambiar el nombre del empleado en mi contrato. Para hacerlo, puedo hacer clic en <em>cualquiera<\/em> de los campos de Empleado duplicados (no necesariamente el original que cre\u00e9 al principio), y simplemente cambiar el contenido. Cuando haga clic fuera de ese campo, todas las instancias de ese campo se actualizar\u00e1n para coincidir con este cambio. \ud83d\udd04<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428010_470_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"Un contrato de muestra, con el nombre del empleado cambiado en todo el texto al ajustar uno de los campos que contiene el nombre del empleado.\" width=\"807\" height=\"373\" title=\"\"><\/figure>\n<p>Los campos duplicados solo se actualizar\u00e1n cuando clickees fuera del campo que est\u00e1s modificando. \u00a1No esperes que cambie en tiempo real mientras escrib\u00eds! \u23f3<\/p>\n<h2 id=\"step-4-save-your-work-as-a-template\">Paso 4: Guardar Tu Trabajo como Plantilla<\/h2>\n<p>Ahora que juntaste tu documento con los campos repetidos que se actualizan autom\u00e1ticamente, guardalo como una plantilla para un uso futuro. Presion\u00e1 F12, dale un nombre adecuado a tu plantilla, cambia el campo Tipo de Guardado a \u00abPlantilla de Word,\u00bb y hac\u00e9 clic en \u00abGuardar.\u00bb \ud83d\udcbe<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428011_958_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"El cuadro de di\u00e1logo &#039;Guardar como&#039; en Microsoft Word, con el nombre de archivo cambiado a &#039;Contrato de Empleo&#039; y el tipo cambiado a &#039;Plantilla de Word&#039;.\" width=\"771\" height=\"559\" title=\"\"><\/figure>\n<p>Ahora, cuando abras una nueva ventana de Word, hac\u00e9 clic en \u00abNuevo\u00bb y localiz\u00e1 tu plantilla. \ud83c\udd95<\/p>\n<figure><img decoding=\"async\" style=\"height: auto; max-width: 100%;\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736428011_987_Como-Repetir-y-Actualizar-Automaticamente-Campos-de-Texto-en-Microsoft.png\" alt=\"La p\u00e1gina de bienvenida de Microsoft Word, con la plantilla del Contrato de Empleo accesible a trav\u00e9s de la pesta\u00f1a de Nuevo.\" width=\"750\" height=\"774\" title=\"\"><\/figure>\n<p>Tan pronto como hagas clic en la plantilla para abrirla, presion\u00e1 F12 para guardarla como un nuevo Documento de Word. Tu documento est\u00e1 ahora listo para que cambies los campos de texto. \ud83d\udd8d\ufe0f<\/p>\n<hr \/>\n<p>Tambi\u00e9n pod\u00e9s agregar otros tipos de campos a un documento de Microsoft Word a trav\u00e9s de la pesta\u00f1a Desarrollador. Por ejemplo, pod\u00e9s insertar listas desplegables, respuestas de texto libre y casillas de verificaci\u00f3n cuando cre\u00e1s un formulario que enviar\u00e1s a otros. \ud83d\udcdd\u27a1\ufe0f<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e33\u0e0b\u0e49\u0e33\u0e41\u0e25\u0e30\u0e2d\u0e31\u0e1b\u0e40\u0e14\u0e15\u0e1f\u0e34\u0e25\u0e14\u0e4c\u0e43\u0e19 Word \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e25\u0e30\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e01\u0e23\u0e2d\u0e01\u0e42\u0e14\u0e22\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e40\u0e27\u0e25\u0e32\u0e41\u0e25\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19!<\/p>","protected":false},"author":1,"featured_media":89464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","iawp_total_views":211,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"1","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":""},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[1435],"tags":[1445,1558,1623],"class_list":["post-32253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutoriales","tag-evergreencontent","tag-techtips","tag-windows10"],"_links":{"self":[{"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/posts\/32253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/comments?post=32253"}],"version-history":[{"count":19,"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/posts\/32253\/revisions"}],"predecessor-version":[{"id":105555,"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/posts\/32253\/revisions\/105555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/media\/89464"}],"wp:attachment":[{"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/media?parent=32253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/categories?post=32253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastertrend.info\/th\/wp-json\/wp\/v2\/tags?post=32253"}],"curies":[{"name":"\u0e2b\u0e19\u0e49\u0e32","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}