{"id":31771,"date":"2025-05-07T23:50:40","date_gmt":"2025-05-08T02:50:40","guid":{"rendered":"https:\/\/mastertrend.info\/?p=31771"},"modified":"2025-11-13T00:20:12","modified_gmt":"2025-11-13T03:20:12","slug":"microsoft-edge-%e5%bf%ab%e6%8d%b7%e6%96%b9%e5%bc%8f","status":"publish","type":"post","link":"https:\/\/mastertrend.info\/zh\/acceso-directo-microsoft-edge\/","title":{"rendered":"Microsoft Edge \u5feb\u6377\u65b9\u5f0f\uff1a\u53ea\u9700 6 \u4e2a\u6b65\u9aa4\u5373\u53ef\u8f7b\u677e\u5b9e\u73b0\u5b8c\u7f8e\u89e3\u51b3\u65b9\u6848 \u26a1\ud83d\udee0\ufe0f"},"content":{"rendered":"<h2>Acceso Directo Microsoft Edge: 6 trucos r\u00e1pidos para eliminarlo \ud83d\udda5\ufe0f\u274c<\/h2>\n<div>\n<p>Aunque Microsoft Edge consume menos recursos del sistema que Chrome, a\u00fan presenta algunos problemas. Recientemente, muchos usuarios de Windows 11 han estado enfrentando inconvenientes con el acceso directo de Microsoft Edge. \ud83d\udda5\ufe0f<\/p>\n<p>Los usuarios de Windows han reportado que el acceso directo de <a href=\"https:\/\/www.microsoft.com\/es-es\/edge\/?form=MA13FJ\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"mentions\">Microsoft Edge<\/a> aparece autom\u00e1ticamente en el escritorio. El problema es que el atajo se presenta incluso despu\u00e9s de eliminarlo. Algunos usuarios en los Foros de Microsoft tambi\u00e9n han mencionado que el acceso directo de Edge vuelve a aparecer tras reiniciar.<\/p>\n<p>Si est\u00e1s utilizando Windows y experimentas el mismo problema, aqu\u00ed te contamos c\u00f3mo solucionarlo. \ud83d\udd27<\/p>\n<h2><span id=\"1_Add_a_new_Registry_entry\"><strong>1. A\u00f1adir una nueva entrada en el Registro<\/strong><\/span><\/h2>\n<p>Este m\u00e9todo a\u00f1adir\u00e1 una nueva entrada al registro de Windows, <span style=\"margin: 0px; padding: 0px;\">evitando<\/span> que el navegador Edge cree accesos directos en tu escritorio. Esto es lo que necesitas hacer:<\/p>\n<p>1. Haz clic derecho en tu escritorio y selecciona <strong>Nuevo &gt; Documento de Texto<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177216\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Nuevo &gt; Documento de Texto\" width=\"600\" height=\"513\" data-lazy-=\"\" title=\"\"><\/p>\n<p>2. En el documento de texto, copia y <strong>pega el siguiente contenido<\/strong>.<\/p>\n<pre>Windows Registry Editor Version 5.00\r\n\r\n[HKEY_LOCAL_MACHINE\\SOFTWARE\\Policies\\Microsoft\\EdgeUpdate]\r\n\"CreateDesktopShortcutDefault\"=dword:00000000\r\n\"RemoveDesktopShortcutDefault\"=dword:00000001<\/pre>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177215\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290467_908_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"pegar el contenido a continuaci\u00f3n\" width=\"600\" height=\"349\" data-lazy-=\"\" title=\"\"><\/p>\n<p>3. Una vez hecho esto, haz clic en el men\u00fa <strong>Archivo<\/strong> en la esquina superior derecha y selecciona la opci\u00f3n <strong>Guardar Como<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177214\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290467_390_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Guardar Como\" width=\"640\" height=\"355\" data-lazy-=\"\" title=\"\"><\/p>\n<p>4. En el cuadro de di\u00e1logo de Guardar como, introduce el nombre del archivo, como prefieras. Sin embargo, aseg\u00farate de que el nombre termine con <strong>.reg<\/strong>. Por ejemplo, <strong>seguro.reg<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177213\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290467_819_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Guardar Como\" width=\"600\" height=\"424\" data-lazy-=\"\" title=\"\"><\/p>\n<p>5. Despu\u00e9s de guardar el archivo .reg, ve a la pantalla del escritorio y haz doble clic en el archivo. Ver\u00e1s un mensaje de confirmaci\u00f3n; haz clic en el bot\u00f3n <strong>S\u00ed<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177212\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290467_959_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"S\u00ed\" width=\"582\" height=\"222\" data-lazy-=\"\" title=\"\"><\/p>\n<h2><span id=\"2_Remove_Microsoft_Edge_as_Default_Browser\"><strong>2. Quitar Microsoft Edge como Navegador Predeterminado<\/strong><\/span><\/h2>\n<p>Cuando estableces un navegador web como predeterminado, le otorgas muchos permisos en el sistema para ejecutar servicios y tareas en segundo plano. As\u00ed que, si tienes Microsoft Edge como <a class=\"wpil_keyword_link\" title=\"Actualizar controladores de audio: \u00a1Consigue mejor sonido! \ud83c\udfb6\" href=\"https:\/\/mastertrend.info\/actualizar-controladores-de-audio\/\" target=\"_blank\" rel=\"noopener\" data-wpil-keyword-link=\"linked\" data-wpil-monitor-id=\"8156\">navegador predeterminado<\/a>, la mejor opci\u00f3n es quitarlo. \u274c<\/p>\n<p>Es f\u00e1cil quitar Microsoft Edge como navegador predeterminado en Windows; solo sigue estos simples pasos:<\/p>\n<p>1. Primero, haz clic en el men\u00fa de inicio de Windows y selecciona <strong>Configuraci\u00f3n<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177211\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290468_92_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Configuraci\u00f3n\" width=\"575\" height=\"600\" data-lazy-=\"\" title=\"\"><\/p>\n<p>2. En Configuraci\u00f3n, cambia a la secci\u00f3n <strong>Aplicaciones<\/strong> en la izquierda.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177210\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290468_459_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Aplicaciones\" width=\"279\" height=\"400\" data-lazy-=\"\" title=\"\"><\/p>\n<p>3. En el lado derecho, haz clic en <strong>Aplicaciones predeterminadas<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177209\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290468_424_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Aplicaciones predeterminadas\" width=\"500\" height=\"396\" data-lazy-=\"\" title=\"\"><\/p>\n<p>4. Utiliza la <strong>barra de b\u00fasqueda para cualquier navegador web<\/strong> que no sea Edge.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177208\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290468_95_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"barra de b\u00fasqueda para cualquier navegador web\" width=\"500\" height=\"416\" data-lazy-=\"\" title=\"\"><\/p>\n<p>5. Luego de seleccionar el navegador web, haz clic en la opci\u00f3n <strong>Establecer predeterminado<\/strong> en la esquina superior derecha.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177207\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290468_118_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Establecer predeterminado\" width=\"800\" height=\"355\" data-lazy-=\"\" title=\"\"><\/p>\n<h2><span id=\"3_Disable_Microsoft_Edge_Running_on_Startup\"><strong>3. Deshabilitar Microsoft Edge en el Inicio<\/strong><\/span><\/h2>\n<p>Si el acceso directo de Microsoft Edge aparece en el escritorio despu\u00e9s de reiniciar, necesitas encontrar y deshabilitar Edge desde la pesta\u00f1a de aplicaciones de inicio del Administrador de tareas. Para hacerlo, sigue estos simples pasos:<\/p>\n<p>1. Primero, haz clic en la b\u00fasqueda de Windows y escribe <strong>Administrador de tareas<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177206\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290468_745_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Administrador de tareas\" width=\"600\" height=\"511\" data-lazy-=\"\" title=\"\"><\/p>\n<p>2. Cuando se abra el Administrador de tareas, cambia a las <strong>aplicaciones de inicio<\/strong> a la izquierda.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177204\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290469_869_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Inicio\" width=\"500\" height=\"484\" data-lazy-=\"\" title=\"\"><\/p>\n<p>3. En el lado derecho, busca y selecciona <strong>msedge.exe<\/strong>.<\/p>\n<p>4. En la esquina superior derecha, haz clic en <strong>Deshabilitar<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177205\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290469_478_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Deshabilitar\" width=\"500\" height=\"485\" data-lazy-=\"\" title=\"\"><\/p>\n<p>Esto evitar\u00e1 que el navegador Microsoft Edge se ejecute al inicio de Windows. A partir de ahora, el acceso directo de Edge no aparecer\u00e1 en el escritorio despu\u00e9s de reiniciar. \ud83d\udeab<\/p>\n<h2><span id=\"4_Disable_Edge_Related_Taks_on_Task_Scheduler\"><strong>4. Deshabilitar tareas relacionadas con Edge en el Programador de tareas<\/strong><\/span><\/h2>\n<p>Microsoft Edge ejecuta muchos procesos en segundo plano. Las tareas programadas para el navegador Edge incluyen verificar actualizaciones, crear un acceso directo en el escritorio, etc. Por lo tanto, las tareas programadas son a menudo las responsables de a\u00f1adir un nuevo acceso directo de Edge en tu escritorio de Windows. \ud83d\uddd3\ufe0f<\/p>\n<p>Por eso, deber\u00e1s acceder al Programador de tareas de Windows y detener todas las tareas relacionadas con Edge. As\u00ed es como puedes hacerlo:<\/p>\n<p>1. Haz clic en la b\u00fasqueda de Windows y escribe <strong>Programador de Tareas<\/strong>. Luego, abre la aplicaci\u00f3n del Programador de Tareas desde la lista de opciones disponibles.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177199\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290469_192_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Programador de tareas\" width=\"600\" height=\"498\" data-lazy-=\"\" title=\"\"><\/p>\n<p>2. Cuando se abra el Programador de tareas, selecciona <strong>Biblioteca del programador de tareas<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177202\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290469_228_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Biblioteca del programador de tareas\" width=\"483\" height=\"500\" data-lazy-=\"\" title=\"\"><\/p>\n<p>3. Ahora, haz clic derecho en <strong>MicrosoftEdgeUpdateTaskMachineCore<\/strong> y deshabil\u00edtalo.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177201\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290469_191_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"MicrosoftEdgeUpdateTaskMachineCore\" width=\"640\" height=\"303\" data-lazy-=\"\" title=\"\"><\/p>\n<p>4. Tambi\u00e9n necesitas deshabilitar el <strong>MicrosoftEdgeUpdateTaskMachineUA<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177200\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290469_428_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"MicrosoftEdgeUpdateTaskMachineUA\" width=\"500\" height=\"388\" data-lazy-=\"\" title=\"\"><\/p>\n<h2><span id=\"5_Make_Changes_to_the_Local_Group_Policy_Editor\"><strong>5. Modificar el Editor de Directivas de Grupo Local<\/strong><\/span><\/h2>\n<p>Tambi\u00e9n puedes hacer algunos cambios en el Editor de Directivas de Grupo Local para evitar que el acceso directo de Microsoft Edge aparezca en tu escritorio. Para hacerlo, sigue estos simples pasos:<\/p>\n<p>1. Primero, haz clic en la b\u00fasqueda de Windows y escribe <strong>Editor de Directivas de Grupo Local<\/strong>. Luego, abre la aplicaci\u00f3n correspondiente de la lista.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177199\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290469_192_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Editor de Directivas de Grupo Local\" width=\"600\" height=\"498\" data-lazy-=\"\" title=\"\"><\/p>\n<p>2. En el Editor de Directivas de Grupo Local, navega a la siguiente ruta:<\/p>\n<pre><strong>Configuraci\u00f3n del ordenador &gt; Plantillas Administrativas &gt; Componentes de Windows &gt; Microsoft Edge.<\/strong><\/pre>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177198\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290470_801_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"navegar a la siguiente ruta\" width=\"455\" height=\"500\" data-lazy-=\"\" title=\"\"><\/p>\n<p>3. En el lado derecho, busca y haz doble clic en la pol\u00edtica <strong>Permitir que Microsoft Edge se precargue al inicio de Windows, cuando el sistema est\u00e9 inactivo, y cada vez que se cierre Microsoft Edge<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177197\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290470_116_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Pol\u00edtica\" width=\"500\" height=\"396\" data-lazy-=\"\" title=\"\"><\/p>\n<p>4. En el cuadro de di\u00e1logo, selecciona <strong>Deshabilitado<\/strong> y haz clic en el bot\u00f3n <strong>Aplicar<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-177196\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2025\/01\/1736290470_69_6-Formas-de-Solucionar-el-Problema-del-Acceso-Directo-de.jpg\" alt=\"Deshabilitado\" width=\"500\" height=\"464\" data-lazy-=\"\" title=\"\"><\/p>\n<h2><span id=\"6_Update_your_Windows_Operating_System\"><strong>6. Actualiza tu Sistema Operativo Windows<\/strong><\/span><\/h2>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-142096\" src=\"https:\/\/mastertrend.info\/wp-content\/uploads\/2024\/12\/1735179711_351_9-Mejores-Maneras-de-Solucionar-el-Problema-de-No-Poder.jpg\" alt=\"Buscar actualizaciones\" width=\"580\" height=\"290\" data-lazy-=\"\" title=\"\"><\/p>\n<p>Si el acceso directo de Microsoft Edge sigue apareciendo en el escritorio incluso despu\u00e9s de seguir todos los m\u00e9todos, necesitas actualizar tu sistema operativo Windows. \ud83d\udce5<\/p>\n<p>Actualizar el sistema operativo es una excelente manera de asegurarte de que tu sistema no tenga errores y tenga las \u00faltimas funciones. Adem\u00e1s, al actualizar Windows se instalar\u00e1n todos los controladores necesarios en tu sistema.<\/p>\n<p>As\u00ed que, si el acceso directo de Microsoft Edge sigue apareciendo en tu escritorio debido a un error del sistema o un problema de software, es hora de actualizar el sistema operativo a trav\u00e9s de Configuraci\u00f3n &gt; Actualizaci\u00f3n de Windows &gt; Buscar Actualizaci\u00f3n. \ud83d\udd04<\/p>\n<p>Estos son algunos de los mejores y m\u00e1s f\u00e1ciles m\u00e9todos para solucionar el problema del acceso directo de <a title=\"Cierre Inesperado de Microsoft Edge en Windows\" href=\"https:\/\/mastertrend.info\/cierre-inesperado-de-microsoft-edge\/\" target=\"_blank\" rel=\"noopener\" data-wpil-monitor-id=\"5720\">Microsoft Edge<\/a> que sigue apareciendo en el escritorio en Windows. D\u00e9janos saber en los comentarios si necesitas m\u00e1s ayuda para solucionar este inconveniente. Adem\u00e1s, si el art\u00edculo te fue \u00fatil, comp\u00e1rtelo con tus amigos. \ud83d\ude0a<\/p>\n<p><!-- CONTENT END 1 --><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft Edge \u5feb\u6377\u65b9\u5f0f\u4e00\u76f4\u663e\u793a\uff1f\u7acb\u5373\u53d1\u73b0 6 \u79cd\u5feb\u901f\u6709\u6548\u7684\u65b9\u6cd5\u5c06\u5176\u4ece\u684c\u9762\u4e0a\u5220\u9664\uff01 \ud83d\ude80\u2728<\/p>","protected":false},"author":1,"featured_media":47513,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ai_generated_summary":"","iawp_total_views":349,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard","override":[{"template":"1","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"1","post_reading_time_wpm":"300","post_calculate_word_method":"str_word_count","show_zoom_button":"1","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","show_comment_section":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post_position":"meta","trending_post_label":"Trending","sponsored_post_label":"Sponsored by","disable_ad":"0","subtitle":""},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"percentage","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":{"view_counter_number":"0","share_counter_number":"0","like_counter_number":"0","dislike_counter_number":"0"},"footnotes":""},"categories":[1435],"tags":[1582,1445,1623],"class_list":["post-31771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutoriales","tag-browsertips","tag-evergreencontent","tag-windows10"],"_links":{"self":[{"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/posts\/31771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/comments?post=31771"}],"version-history":[{"count":23,"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/posts\/31771\/revisions"}],"predecessor-version":[{"id":105213,"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/posts\/31771\/revisions\/105213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/media\/47513"}],"wp:attachment":[{"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/media?parent=31771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/categories?post=31771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mastertrend.info\/zh\/wp-json\/wp\/v2\/tags?post=31771"}],"curies":[{"name":"\u53ef\u6e7f\u6027\u7c89\u5242","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}